{"id":317,"date":"2015-10-30T11:24:00","date_gmt":"2015-10-30T11:24:00","guid":{"rendered":"http:\/\/face.unt.edu.ar\/web\/posgrados\/?page_id=317"},"modified":"2015-10-30T15:28:10","modified_gmt":"2015-10-30T15:28:10","slug":"esp-en-tributacion","status":"publish","type":"page","link":"https:\/\/face.unt.edu.ar\/web\/posgrados\/esp-en-tributacion\/","title":{"rendered":"Tributaci\u00f3n"},"content":{"rendered":"<p><strong>Cat\u00e1logo de libros de la Especializaci\u00f3n en Tributaci\u00f3n<\/strong><\/p>\n<p><strong>Municipales <\/strong><\/p>\n<p>Tasas Municipales -TOMO I &#8211; Enrique Bulit Go\u00f1e -Lexis Nexis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Tasas Municipales -TOMO II -Enrique Bulit Go\u00f1e -Lexis Nexis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Tasas Municipales en el Ambito Tributario &#8211; Lorena Almada y Cecilia Matich &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2009<\/p>\n<p>Impuestos Sobre Los Bienes Personales &#8211; Luis Omar Fern\u00e1ndez &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Comercio\u00a0 Electronico<\/strong><\/p>\n<p>Comercio Electr\u00f3nico &#8211; Larry Chass &#8211; Limusa Wiley &#8211; A\u00f1o 2002<\/p>\n<p>Comercio Electronico y Firma Digital &#8211; Mauricio Devoto \u00a0&#8211; La Ley &#8211; Ano 2001<\/p>\n<p>Tributaci\u00f3n en el Comercio Electronico &#8211; Silvina Roldan &#8211; \u00a0&#8211; Osmar Buyatti &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Comercio Electronico- Analisis Juridico Multidiciplinario &#8211; \u00a0\u00a0&#8211; S.Rippe Creimer Del piazzo otros \u2013 BDEF 2003<\/p>\n<p>Equiparaci\u00f3n del Comercio Electronico en el Derecho Civil &#8211; Pedro Gomez &#8211; Nova Tesis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Internet Comercio Electronico y Sociedad de la Informaci\u00f3n &#8211; Adriana Dreyzin de Klor \u2013Boiteucx\u00a0 &#8211; A\u00f1o 2006<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Comercio Internacional \u00a0<\/strong><\/p>\n<p>Los Impuestos y el Comercio Exterior Argentino &#8211; Alfredo Stornberg -Aplicaci\u00f3n Tributaria S.A. &#8211; 2\u00b0 Edicion A\u00f1o 2002<\/p>\n<p>El Comercio Internacional de Mercader\u00edas \u00a0&#8211; Aldo Fratalocchi _ Gustavo Zunino &#8211; Ediciones Buyatti &#8211; A\u00f1o 1997<\/p>\n<p>Delito de Contrabando y Comercio Exterior &#8211; Pedro Medrano &#8211; Libreros Loznes &#8211; A\u00f1o 1991<\/p>\n<p>Como Importar y Exportar \u00a0&#8211; Aldo Fratalocchi &#8211; Errepar S.A. &#8211; A\u00f1o 2002<\/p>\n<p>Como Importar y Exportar &#8211; Aldo Fratalocchi &#8211; Errepar S.A. &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Como Importar y Exportar &#8211; Aldo Fratalocchi &#8211; Errepar S.A. &#8211; 2\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Como Importar y Exportar &#8211; Aldo Fratalocchi &#8211; Errepar S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2005<\/p>\n<p>Negociaciones y Contratacion Internacional &#8211; Anibal Sierralta R\u00edos \u2013 Legis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Estudios de Derecho Internacional Tributario &#8211; Juan Pablo Godoy &#8211; Legis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Contratos de Comercio Exterior &#8211;\u00a0 Aldo Fatalocchi &#8211; Ediciones Macchi &#8211; A\u00f1o 1994<\/p>\n<p>La Tributacion sobre el comercio electr\u00f3nico &#8211; Charles E. Mc Lure &#8211; Giampaolo Corabi Depalma &#8211; 1\u00b0 Edici\u00f3n &#8211; \u00a0A\u00f1o 2000<\/p>\n<p>Impuestos Sobre el Comercio Internacional &#8211; Victor Uckmar\u00a0 &#8211; Heleno Taveira Torres &#8211; Marcial Pons &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Impuestos Sobre el Comercio Internacional \u00a02\u00ba Edicion &#8211; Victor Uckmar\u00a0\u00a0 Heleno Taveira Torres &#8211; Marcial Pons &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Mercosur &#8211; Centro de Econ\u00f3mia Internacional &#8211; \u00a0&#8211; Di-Tela &#8211; A\u00f1o 1994<\/p>\n<p>Marketing y Comercio Exterior &#8211; Aldo Fratalocchi &#8211; Ed. Cangallo \u00a0&#8211; A\u00f1o 1993<\/p>\n<p>Principio de Comercio Internacional &#8211; Carlos Ledesma &#8211; Ediciones Macchi &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 1990<\/p>\n<p>La Armonizaci\u00f3n Tributaria y la Integraci\u00f3n Econ\u00f3mica I &#8211; Dr. Hugo Gonzalez Cano \u2013 Interoce\u00e1nica- A\u00f1o 1994<\/p>\n<p>La Armonizaci\u00f3n Tributaria y la Integraci\u00f3n Econ\u00f3mica II &#8211; Dr. Hugo Gonzalez Cano \u2013 Interoce\u00e1nica &#8211; \u00a0&#8211; A\u00f1o 1994<\/p>\n<p>Revista de Derecho en el Mercosur &#8211; La Ley &#8211; La Ley &#8211; A\u00f1o 1997<\/p>\n<p>Comercio Exterior &#8211; Eduardo Ablin &#8211; Adrian Makuc &#8211; Errepar S.A. &#8211; A\u00f1o 1997<\/p>\n<p>Armonizaci\u00f3n Tributaria del Mercosur &#8211; Hugo Gonzalez Cano &#8211; Ediciones Academicas &#8211; A\u00f1o 1996<\/p>\n<p>Armonizaci\u00f3n Tributaria del Mercosur &#8211; Hugo Gonzalez Cano &#8211; Ediciones Academicas &#8211; A\u00f1o 1997<\/p>\n<p>Armonizaci\u00f3n Tributaria del Mercosur &#8211; Hugo Gonzalez Cano &#8211; Ediciones Academicas &#8211; A\u00f1o 1998<\/p>\n<p>Aspectos Tributario Relativos al Mercosur &#8211; Juan Gomez Sabaini &#8211;\u00a0 &#8211;<\/p>\n<p>Manuel de Tributaci\u00f3n para Importaciones y Exportaciones &#8211; Alfredo Ricardo Sternberg &#8211; Ediciones IARA S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p>Tratado de Derecho Internacional Tributario &#8211; Tomo II &#8211; Ruben Asorey &#8211; Fernando Garcia &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p>Tratado de Derecho Internacional Tributario &#8211; Tomo II &#8211; Ruben Asorey &#8211; Fernando Garcia &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p>Tratado de Derecho Internacional Tributario-Tomo II &#8211; Ruben Asorey &#8211; Fernando Garcia &#8211; La Ley -1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p>C\u00f3digo Aduanero Tomo I &#8211; Pedro Fernandez Lalanne &#8211; Guia Pr\u00e1ctica &#8211; A\u00f1o 1988<\/p>\n<p>C\u00f3digo Aduanero Tomo II &#8211; Pedro Fernandez Lalanne &#8211; Guia Pr\u00e1ctica &#8211; A\u00f1o 1988<\/p>\n<p>C\u00f3digo Aduanero &#8211; A-Z &#8211; &#8211; A-Z &#8211; A\u00f1o 1993<\/p>\n<p>C\u00f3digo Aduanero Tomo I &#8211; Pedro Fernandez Lalanne &#8211; Guia Pr\u00e1ctica &#8211; A\u00f1o 1992<\/p>\n<p>C\u00f3digo Aduanero Tomo II &#8211; Pedro Fernandez Lalanne &#8211; Guia Pr\u00e1ctica &#8211; A\u00f1o 1992<\/p>\n<p>Derecho Aduanero &#8211; Ricardo Basald\u00faa &#8211; Editorial Abeledo Perrot &#8211; A\u00f1o 1992<\/p>\n<p>Como Exportar e Importar &#8211; Aldo Fratalocchi &#8211; Cangallo &#8211; A\u00f1o 1994<\/p>\n<p>Comercio Internacional y Para\u00edsos Fiscales &#8211; Pablo Arrabal &#8211; Editorial Pir\u00e1mide \u2013 A\u00f1o 1992<\/p>\n<p>Mercosur &#8211; Ra\u00fal Roa &#8211; Asoc. Mutual Federal de la DGI &#8211; A\u00f1o 1993<\/p>\n<p>El Mercosur y el Desaf\u00edo \u00a0&#8211; Ing. Guido Di Tella -\u00b4CEI &#8211; A\u00f1o 1987<\/p>\n<p>Est. Argentina p\/el estudio del Mercosur &#8211; Ing. Guido Di Tella \u2013 CEI &#8211; A\u00f1o 1988<\/p>\n<p>Aspectos Internacionales de la Tributaci\u00f3n Argentina &#8211; Gabriel Gotlib &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2005<\/p>\n<p>Tratado de Derecho Internacional Tributario-Tomo III &#8211; Ruben Asorey &#8211; Fernando Garcia &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p>Normas Internacionales de Contabilidad (NICSP) del Sector P\u00fablico &#8211; Luis T\u00e9llez Mellado \u2013 Legis &#8211; 1\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Codigo Penal <\/strong><\/p>\n<p>Codigo Penal De La Naci\u00f3n &#8211; Mario ChiChizola &#8211; Lexis Nexis(Abeledo-Perrot) &#8211; A\u00f1o 2004<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Codigos <\/strong><\/p>\n<p>C\u00f3digo Procesal, Civil y Comercial de la Naci\u00f3n &#8211; Jos\u00e9 Antonio GranGrasso \u2013 Depalma &#8211; A\u00f1o 1997<\/p>\n<p>C\u00f3digo Procesal, Civil y Comercial de la Naci\u00f3n\u00a0 &#8211; Tomo I &#8211; Marcelo Bourguignon &#8211; Juan Peral \u2013 Bibliotex &#8211; 1\u00ba Edicion 2008<\/p>\n<p>C\u00f3digo Procesal, Civil y Comercial de la Naci\u00f3n &#8211; Tomo II &#8211; Juan Peral &#8211; Juana Ines Hael- Bibliotex &#8211; 1\u00ba Edicion 2011<\/p>\n<p>C\u00f3digo Procesal, Civil y Comercial de la Naci\u00f3n .\u00a0 Tomo I &#8211; Roland Arazi &#8211; Jorge Rojas &#8211; Rubinzal Culzoni Editores &#8211; 2\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p>C\u00f3digo Procesal, Civil y Comercial de la Naci\u00f3n . Tomo II &#8211; Roland Arazi &#8211; Jorge Rojas &#8211; Rubinzal Culzoni Editores<\/p>\n<p>C\u00f3digo Procesal, Civil y Comercial de la Naci\u00f3n . Tomo III &#8211; Roland Arazi &#8211; Jorge Rojas &#8211; Rubinzal Culzoni Editores<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; \u00a0&#8211; Roberto Dromi &#8211; &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; \u00a0&#8211; Roberto Dromi &#8211; &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; Roberto Dromi &#8211; &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; Roberto Dromi &#8211; &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; Roberto Dromi &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; Roberto Dromi &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; Roberto Dromi &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo del Mercosur- Tratado-Protocoloa-Acuerdos-Declaraciones- Decisiones- Resoluciones- Directivas- Recomendaciones &#8211; Roberto Dromi &#8211; Ciudad Argentina &#8211; A\u00f1o 1996<\/p>\n<p>Codigo Civil de la Republica Argentina &#8211; Con Legislaci\u00f3n Complementaria &#8211; La Ley &#8211; 7\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p>Codigo Procesal Civil y Comercial de la Naci\u00f3n &#8211; Con Legislaci\u00f3n Complementaria &#8211; La Ley &#8211; 6\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p>Codigo de Comercio &#8211; Con Legislaci\u00f3n Complementaria &#8211; La Ley &#8211; 7\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p>C\u00f3digo Procesal Civil y Comercial de Tucum\u00e1n &#8211; TOMO I- Comentado y Anotado &#8211; \u00a0&#8211; Marcelo Bourguignon &#8211; Juan Peral\u00a0 &#8211; Bibliotex &#8211; 2\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>C\u00f3digo Procesal Civil y Comercial de Tucum\u00e1n &#8211; TOMO II- Comentado y Anotado &#8211; Marcelo Bourguignon &#8211; Juan Peral \u2013 Bibliotex &#8211; 2\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Comercio Electronico &#8211; Ricardo L. Lorenzetti &#8211; Abeledo- Perrot &#8211; A\u00f1o 2001<\/p>\n<p>Convenio Multilateral &#8211; Silvia Grenabuena \u2013 Aplicaci\u00f3n &#8211; 11\u00ba Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Convenio Multilateral &#8211; \u00a0&#8211; Mario Altahabe &#8211; Alejandra Sanelli &#8211; La Ley &#8211; 3\u00ba Edici\u00f3n A\u00f1o 2013<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Derecho <\/strong><\/p>\n<p>El tributo y su Aplicaci\u00f3n.Perspectivas para el siglo XXI &#8211; Tomo I &#8211; Cesar Garcia Novoa &#8211; Catalina Hoyos &#8211; Marcial Pons -1\u00ba Edici\u00f3n A\u00f1o 2008<\/p>\n<p>El tributo y su Aplicaci\u00f3n.Perspectivas para el siglo XXI &#8211; Tomo II &#8211; Cesar Garcia Novoa &#8211; Catalina Hoyos &#8211; &#8211; Marcial Pons &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Derecho Administrativo &#8211; Juan Cassagne &#8211; A_Perrot &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 1991<\/p>\n<p>Derecho Administrativo &#8211; Juan Cassagne &#8211; A_Perrot &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 1991<\/p>\n<p>Cursos de Derecho Administrativo &#8211; Tomo I &#8211; Carlos Balb\u00edn &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Cursos de Derecho Administrativo &#8211; Tomo II &#8211; Carlos Balb\u00edn &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Acci\u00f3n y Recursos en Materia Tributaria &#8211; Rodolfo Spisso &#8211; Lexis Nexis &#8211; &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2005<\/p>\n<p>Acci\u00f3n y Recursos en Materia Tributaria &#8211; Rodolfo Spisso &#8211; Abeledo \u2013 Perrot &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Derecho Financiero (Volumen I) &#8211; Giuliari Fonrouge _ Navarrine y Asorey \u2013 Depalma &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 1993<\/p>\n<p>Derecho Financiero (Volumen II) &#8211; Giuliari Fonrouge _ Navarrine y Asorey \u2013 Depalma &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 1994<\/p>\n<p>Derecho Financiero\u00a0 Tomo I &#8211; Giuliari Fonrouge _ Navarrine y Asorey &#8211; La Ley &#8211; 10\u00b0 Edici\u00f3n A\u00f1o 1995<\/p>\n<p>Derecho Financiero\u00a0 Tomo II &#8211; Giuliari Fonrouge _ Navarrine y Asorey &#8211; La Ley &#8211; 10\u00b0 Edici\u00f3n A\u00f1o 1996<\/p>\n<p>Derecho Tributario Penal &#8211; Dr. Garcia Belsunce &#8211; Depalma &#8211; A\u00f1o 1985<\/p>\n<p>Estudio sobre el Proceso Penal Tributario &#8211; Hernande Llanos-Vicente Oscar D\u00edaz-Teresa Gomez- Marcos Grabivker &#8211; Errepar S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>II jornada de Derecho Penal Tributario &#8211; Variois autores &#8211; Errepar S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p>IV jornada de Derecho Penal Tributario &#8211; Variois autores &#8211; Errepar S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2009<\/p>\n<p>Manual de Derecho Penal Tributario &#8211; Graciela Nora Manonellas &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2009<\/p>\n<p>Nociones fundamentales de derecho tributario &#8211; Juan Rafael Bravo Arteaga \u2013 Legis &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Estado de Derecho y Sistema Penal &#8211; Carlos Alberto Chiara Diaz &#8211; Carlos Maria Folco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Ensayo de Derecho Penal Tributario \u00a0&#8211; Dr Vicente Oscar Diaz &#8211; Errepar S.A. &#8211; A\u00f1o 1995<\/p>\n<p>Instituciones de Derecho Tributario &#8211; Ram\u00f3n Valdes Costa \u2013 Depalma &#8211; A\u00f1o 1992<\/p>\n<p>Presunciones y Ficciones en el Derecho Tributario &#8211; Susana Navarrine y Ruben Asorey \u2013 Depalma &#8211; A\u00f1o 1985<\/p>\n<p>Tributaci\u00f3n Local Provincial y Municipal &#8211; Tomo I &#8211; Jun Manuel Alvarez Echag\u00fce &#8211; AD-HOC &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tributaci\u00f3n Local Provincial y Municipal &#8211; Tomo II &#8211; Jun Manuel Alvarez Echag\u00fce &#8211; AD-HOC &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Temas de Derecho Tributario &#8211; Dr. Garcia Belsunce \u2013 Perrot &#8211; A\u00f1o 1982<\/p>\n<p>Estudio de Derecho P\u00fablico &#8211; J. Carlos Cassagne &#8211; Depalma &#8211; A\u00f1o 1995<\/p>\n<p>C\u00f3digo Procesal Penal Ley 23984 Tomo I \u2013 Ramirez \u2013 Universidad &#8211; 2\u00b0 Edici\u00f3n A\u00f1o 1996<\/p>\n<p>C\u00f3digo Procesal Penal Ley 23984 Tomo II \u2013 Ramirez \u2013 Universidad &#8211; 2\u00b0 Edici\u00f3n A\u00f1o 1996<\/p>\n<p>Derecho Financiero \u00a0&#8211; Horacio Corti \u00a0&#8211; Editorial Abeledo Perrot &#8211; A\u00f1o 1997<\/p>\n<p>Los Derechos de\u00a0 Aduana &#8211; Julio Carlos Lascano \u2013 Buyatti &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Curso de Derecho Tributario \u00a0&#8211; Dino Jarach &#8211; Editorial Cima &#8211; 8\u00b0 Edici\u00f3n A\u00f1o 1980<\/p>\n<p>Manual del Derecho Tributario &#8211; Mario A. Saccone &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p>Manual del Derecho Tributario Internacional &#8211; Victor Uckmar y otros &#8211; La Ley &#8211; \u00a0&#8211; 1\u00ba Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Dercho Tributario y Derecho Privado &#8211; Heleno Taveira Torres &#8211; Marcial Pons &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Dercho Tributario &#8211; Alejandro Altamirano &#8211; Marcial Pons &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Elemento de Derecho Empresarial &#8211; Gaston O&#8217;donnell &#8211; Ediciones Macchi &#8211; A\u00f1o 1995<\/p>\n<p>La Autonomia del Derecho Tributario &#8211; Dr. Garcia Belsunce &#8211; Depalma &#8211; A\u00f1o 1996<\/p>\n<p>Derecho Tributario General &#8211; Jos\u00e9 M. Mart\u00edn &#8211; Us\u00e9 &#8211; Depalma &#8211; 2\u00b0 Edici\u00f3n A\u00f1o 1995<\/p>\n<p>Dercho Tributario Provincial y Municipal &#8211; Esteban Urresti &#8211; AD-HOC &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Dercho Tributario\u00a0 &#8211; Tomo I &#8211; Catalina Garcia Vizcaino &#8211; Abeledo &#8211; Perrot &#8211; 5\u00ba Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Dercho Tributario\u00a0 &#8211; Tomo II &#8211; Catalina Garcia Vizcaino &#8211; Abeledo &#8211; Perrot &#8211; 5\u00ba Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Dercho Tributario &#8211; Tomo III &#8211; Catalina Garcia Vizcaino &#8211; Abeledo &#8211; Perrot &#8211; 4\u00ba Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Concepto de Tributo &#8211; Cesar Garcia Novoa &#8211; Marcial Pons &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Temas Basicos de Derecho Penal \u00a0&#8211; Sebastian Soler \u00a0&#8211; Abeledo &#8211; Perrot &#8211; A\u00f1o 1977<\/p>\n<p>Derecho Procesal Penal Tributario &#8211; Jos\u00e9 A. Viola \u00a0&#8211; La Ley &#8211; A\u00f1o 2003<\/p>\n<p>Sanciones en cubiertas en el Derecho Tributario &#8211; Jos\u00e9 Litvak &#8211; Anal\u00eda Sanchez &#8211; La Ley &#8211; A\u00f1o 2003<\/p>\n<p>Derecho Financiero Tomo I &#8211; Carlos Giulliane &#8211; Fonrouse &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p>Derecho Financiero Tomo II &#8211; Carlos Giulliane &#8211; Fonrouse &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p>Derecho Tributario &#8211; Manual Practico &#8211; Gustavo Atim &#8211; Ezequiel Stordeur &#8211; Osmar D. Buyatti &#8211; 1\u00ba edici\u00f3n A\u00f1o 2013<\/p>\n<p>Derecho Tributario (Fundamentos Juridicos de la Incidencia &#8211; Paulo de Barros Carvalho &#8211; \u00c1baco de Rodolfo Depalma &#8211; A\u00f1o 2004<\/p>\n<p>El Acto Administrativo Tributario &#8211; Mar\u00eda Jos\u00e9 Rodriguez &#8211; \u00c1baco de Rodolfo Depalma &#8211; A\u00f1o 2004<\/p>\n<p>Vicios y mitos de la interpretaci\u00f3n tributaria &#8211; Gabriel Gotlib &#8211; \u00c1baco de Rodolfo Depalma &#8211;<\/p>\n<p>La Autoria en los Delitos Tributarios &#8211; Carolina Robliglio &#8211; AD-HOC &#8211;<\/p>\n<p>La Clausura En Materia Tributaria &#8211; Ju\u00e1n \u00c1lvarez Echag\u00fce &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2002<\/p>\n<p>Procedimiento Tributario 1 (Cuaderno) &#8211; Teresa Gomez &#8211; Carlos Folco &#8211; Nuevas Tecnicas S.R.L. &#8211; 4\u00baedici\u00f3n A\u00f1o 2005<\/p>\n<p>Derecho Tributario Procesal \u00a0&#8211; Jos\u00e9 Mart\u00edn &#8211; Guillermo Rodriguez &#8211; Us\u00e9 \u00a0&#8211; 2\u00b0 Edici\u00f3n A\u00f1o 1987<\/p>\n<p>La consulta Tributaria Vinculante &#8211; Humberto Bertazza &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Derecho Constitucional <\/strong><\/p>\n<p>Derecho Constitucional \u00a0&#8211; Rodolfo R Spisso &#8211; Depalma &#8211; A\u00f1o 1993<\/p>\n<p>Derecho Constitucional Tributario &#8211; Rodolfo Spisso &#8211; Lexis Nexis ( Depalma) &#8211; 2\u00ba edici\u00f3n A\u00f1o 2000<\/p>\n<p>Derecho Constitucional Tributario &#8211; Rodolfo Spisso &#8211; Lexis Nexis &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Constituci\u00f3n de la Naci\u00f3n Argentina &#8211; Graciela Pinese &#8211; Pablo Corbal\u00e1n &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p>Constituci\u00f3n de la Naci\u00f3n y Tributacion Local &#8211; Tomo I &#8211; Enrique Bulit Go\u00f1i &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p>Constituci\u00f3n de la Naci\u00f3n y Tributacion Local &#8211; Tomo II &#8211; Enrique Bulit Go\u00f1i &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p>Constituci\u00f3n de la Naci\u00f3n y Tributacion Local &#8211; Tomo I &#8211; Enrique Bulit Go\u00f1i &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p>Constituci\u00f3n de la Naci\u00f3n y Tributacion Local &#8211; Tomo II &#8211; Enrique Bulit Go\u00f1i &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p>Derechos y Garantias Constitucionales del Contribuyente &#8211; Jos\u00e9 Osvaldo Cas\u00e1s &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2005<\/p>\n<p>El principio Constitucional de no Confiscatoriedad Tributaria &#8211; Gustavo Naveyra de Casanova &#8211; Abeledo &#8211; Perrot &#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Derecho Constitucional Tributario &#8211; tomo 1 &#8211; Eduardo Baistrocchi &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2013<\/p>\n<p>Derecho Constitucional Tributario &#8211; tomo 2 &#8211; Eduardo Baistrocchi &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2013<\/p>\n<p>Control de Constitucionalidad en la Provincia de Tucuman &#8211; Juana In\u00e9s Hael de Mauvec\u00edn &#8211; Bibliotex &#8211; 1\u00ba edici\u00f3n A\u00f1o 2014<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Derecho e Impuestos al Valor Agregado <\/strong><\/p>\n<p>Tratado Jurisprudencial y Doctrinario &#8211; Tomo I &#8211; Derecho e Impuesto al valor agregado &#8211; Joege Damarco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tratado Jurisprudencial y Doctrinario &#8211; Tomo I &#8211; Derecho e Impuesto al valor agregado &#8211; Joege Damarco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Derecho Tributario <\/strong><\/p>\n<p>El Hecho Imponible &#8211; Dino Jarach &#8211; Abeledo &#8211; Perrot &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Regimen Tributario de la Actuaci\u00f3n Notarial &#8211; Viviana Di Pietromioca &#8211; Lexis Nexis &#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>La responsabilidad del Estado por Actos de Contenido Tributario &#8211; Jos\u00e9 Osvaldo Cas\u00e1s &#8211; AD-HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Derecho Ambiental Profundizado &#8211; Eduardo A. Pigretti &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p>Derecho Ambiental y Da\u00f1o &#8211; Ricardo Luis Lorenzetti &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p>Teoria del Derecho Ambiental &#8211; Ricardo Luis Lorenzetti &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>Los Contratos en el Derecho Privado &#8211; Fabricio Martilla Espinosa &#8211; Francisco Ternera Barrios &#8211; 1\u00ba Edici\u00f3n \u00a0&#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>Revista Juridica Argentina Derecho Trib.Doctrina Esenciales &#8211; Tomo I &#8211; Susana Camila Navarrine &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Revista Juridica Argentina Derecho Trib.Doctrina Esenciales &#8211; Tomo II &#8211; Susana Camila Navarrine &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Revista Juridica Argentina Derecho Trib.Doctrina Esenciales &#8211; Tomo II &#8211; Susana Camila Navarrine &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Derecho Tributario &#8211; Gustavo Naveira &#8211; Editorial Estudio &#8211; 1\u00ba edici\u00f3n A\u00f1o 2013<\/p>\n<p>Derecho Tributario &#8211; Gustavo Naveira &#8211; Editorial Estudio<\/p>\n<p>Derecho Tributario &#8211; Gustavo Naveira &#8211; Editorial Estudio<\/p>\n<p>Derecho Tributario &#8211; Gustavo Naveira &#8211; Editorial Estudio<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Derecho y Ganancias <\/strong><\/p>\n<p>Tratado Jurisprudencial y Doctrinario &#8211; Tomo I &#8211; Joege Damarco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tratado Jurisprudencial y Doctrinario &#8211; Tomo II &#8211; Joege Damarco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tratado Jurisprudencial y Doctrinario &#8211; Tomo II &#8211; Joege Damarco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tratado Jurisprudencial y Doctrinario &#8211; Tomo II &#8211; Derecho y Regimen Penal Tributario &#8211; Joege Damarco &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Econom\u00eda <\/strong><\/p>\n<p>Malestar en las Econ\u00f3mias Modernas de Mercado &#8211; Dr. Hugo Ferrullo &#8211; Ediciones Macchi &#8211; A\u00f1o 2000<\/p>\n<p>Malestar en las Econ\u00f3mias Modernas de Mercado &#8211; Dr. Hugo Ferrullo &#8211; Ediciones Macchi &#8211; A\u00f1o 2000<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Fideicomiso <\/strong><\/p>\n<p>Tratado de Fideicomiso &#8211; Claudio M. Kiper &#8211; Silvio V. Lisoprawski &#8211; Lexis Nexis (Depalma) &#8211; 2\u00ba edici\u00f3n A\u00f1o 2004<\/p>\n<p>Aspecto Tributarios del Fideicomiso &#8211; Alberto P. Coto &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Aspecto Tributarios del Fideicomiso &#8211; Alberto P. Coto &#8211; La Ley &#8211; 2\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Manual Pr\u00e1ctico de Fideicomiso &#8211; Juli\u00e1n Nerotti \u00a0&#8211; Nova Tesis &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Negocios Fiduciarios &#8211; Sergio Rodriguez Azuero &#8211; Legis &#8211; 1\u00ba edici\u00f3n A\u00f1o 2005<\/p>\n<p>Fideicomiso &#8211; Julian Martin,Eidelstein,Alchouron &#8211; Errepar \u00a0&#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Fideicomiso &#8211; Julian Martin,Eidelstein,Alchouron &#8211; Errepar \u00a0&#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Fideicomiso &#8211; Mario Carregal &#8211; Heliasta &#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>Fideicomiso &#8211; Ley 24.441 &#8211; Lydia Calegari de Grosso &#8211; La Ley &#8211; 2\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>El Fideicomiso de Garantia &#8211; Guillermo Cabanellas de las cuevas y Gabriel de Reina Tartiere &#8211; Heliasta &#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>Ley de Fideicomiso Comentada &#8211; Manuel Alejandro Am\u00e9ndola &#8211; Errepar \u00a0&#8211; 1\u00ba edici\u00f3n A\u00f1o 2011<\/p>\n<p>Fideicomiso de Costruccion &#8211; Julian Ruiz &#8211; Osmar Buyatti &#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>Financiamiento y Fideicomiso Tratamiento Tributario &#8211; Leonardo H. Hansen &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Finanzas \u00a0<\/strong><\/p>\n<p>Cursos de Finanzas, Derecho Financiero y Tributario \u00a0&#8211; Dr Hector Villegas &#8211; Depalma &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 1993<\/p>\n<p>Cursos de Finanzas, Derecho Financiero y Tributario \u00a0&#8211; Dr Hector Villegas &#8211; Depalma &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 1993<\/p>\n<p>Hacienda P\u00fablica Te\u00f3rica Aplicada &#8211; Richard Musgrave &#8211; McGraw-Hill &#8211; 5\u00b0 Edici\u00f3n<\/p>\n<p>Hacienda P\u00fablica Te\u00f3rica Aplicada &#8211; Richard Musgrave &#8211; McGraw-Hill &#8211; 5\u00b0 Edici\u00f3n<\/p>\n<p>La Econ\u00f3mia del Sector P\u00fablico &#8211; Stiglitz &#8211; Antoni Boch &#8211; 2\u00b0 Edici\u00f3n A\u00f1o 1995<\/p>\n<p>Finanzas P\u00f9blicas y Derecho Tributario &#8211; Dino Jarach &#8211; La Ley &#8211; 3\u00b0 Edici\u00f3n<\/p>\n<p>Finanzas P\u00f9blicas y Derecho Tributario &#8211; Dino Jarach &#8211; La Ley &#8211; 1\u00ba Edicion 2007<\/p>\n<p>Finanzas P\u00f9blicas y Derecho Tributario &#8211; Dino Jarach &#8211; La Ley &#8211; 2\u00ba Edicion 2007<\/p>\n<p>Finanzas P\u00f9blicas y Derecho Financiero &#8211; Gustavo Naveira &#8211; Editorial Estudio &#8211; 2\u00ba Edicion 2013<\/p>\n<p>Finanzas P\u00f9blicas \u00a0&#8211; Horacio Nu\u00f1ez Mi\u00f1ana &#8211; Ediciones Macchi<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Firma Digital \u00a0<\/strong><\/p>\n<p>Firma Digital &#8211; Pablo Farr\u00e9s (Serie de Legislac. Comentada &#8211; Lexis Nexis &#8211; 1\u00ba edici\u00f3n A\u00f1o 2005<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Ganancias <\/strong><\/p>\n<p>Impuesto a las Ganancias \u00a0&#8211; Enrique Jorge Reig \u00a0&#8211; Edici\u00f3n Macchi &#8211; 9\u00b0 Edici\u00f3n A\u00f1o 1996<\/p>\n<p>Impuesto a las Ganancias &#8211; Enrique Jorge Reig \u00a0&#8211; Edici\u00f3n Macchi &#8211; 9\u00b0 Edici\u00f3n Act. A\u00f1o 1998<\/p>\n<p>Tratado de Impuesto a las Ganancias &#8211; Armando Lorenzo y Otros \u00a0&#8211; Errepar S.A. &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2005<\/p>\n<p>Impuesto a las Ganancias &#8211; Enrique Jorge Reig \u00a0&#8211; Edici\u00f3n Macchi &#8211; 11\u00ba Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Impuesto a las Ganancias (Impuestos Comentados) &#8211; Dr. Ernesto Celdeiro &#8211; Errepar S.A. &#8211; Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Impuesto a las Ganancias (Impuestos Comentados) &#8211; Dr. Ernesto Celdeiro &#8211; Errepar S.A. &#8211; Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Impuesto a las Ganancias (Impuestos Comentados) &#8211; Dr. Ernesto Celdeiro &#8211; Errepar S.A. &#8211; Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Impuesto a las Ganancias,Analicis a la Doctrina y Jurisprudencia &#8211; Carlos Fonrouge Giuliano &#8211; LexisNexis &#8211; 4\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Impuesto a las Ganancias\u00a0 Analisis de Doctrina y Jurisprudencia &#8211; Carlos Fonrouge &#8211; Susana Navarrine &#8211; LexisNexis &#8211; 4\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Manual de Impuestos\u00a0 a\u00a0 Las Ganancias &#8211; Dario Rajmilovich &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2006<\/p>\n<p>Impuesto a las Ganancias \u00a0&#8211; Gustavo E. Diez &#8211; La Ley &#8211; 3\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Impuesto a las Ganancias \u00a0&#8211; Gustavo E. Diez &#8211; La Ley &#8211; 4\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Impuestos a las Ganancias (Minima Presunta) &#8211; Luis Omar Fern\u00e1ndez &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>El Impuesto a las Ganancias &#8211; Carlos Raimondi _ Adolfo Atchabahin &#8211; Depalma &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2000<\/p>\n<p>El Impuesto a las Ganancias &#8211; Carlos Raimondi _ Adolfo Atchabahin &#8211; Depalma &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2000<\/p>\n<p>Registro de Entidades Exentas del Impuesto a Las Ganancias \u00a0&#8211; Ram\u00f3n Pe\u00f1a &#8211; Felix G. Guerrieri &#8211; Buyatti &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2005<\/p>\n<p>Impuestos a las Ganancias (Teor\u00eda- Tecnica-Practica) &#8211; Luis Omar Fern\u00e1ndez &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2005<\/p>\n<p>Impuestos a las Ganancias (Teor\u00eda- Tecnica-Practica) &#8211; Luis Omar Fern\u00e1ndez &#8211; La Ley &#8211; 2\u00ba Edici\u00f3n A\u00f1o 2005<\/p>\n<p>Impuestos a las Ganancias estudio(Teor\u00edco-Practico) &#8211; Enrique Reig &#8211; Jorge Gebhardt &#8211; Ruben Malvitano &#8211; Errepar S.A. &#8211; 12\u00ba Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Impuestos a las Ganancias (Minima Presunta) &#8211; Luis Omar Fern\u00e1ndez &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Ley de Impuesto a las Ganancias &#8211; Alfredo Lamagrande &#8211; La Ley &#8211; 2\u00ba Edici\u00f3n A\u00f1o 2009<\/p>\n<p>El Impuesto a las Ganancias &#8211; Carlos Raimondi _ Adolfo Atchabahin &#8211; La Ley &#8211; 5\u00ba Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Impuesto a las Ganancias &#8211; Luis Omar Fern\u00e1ndez &#8211; La Ley &#8211; 2\u00ba Edici\u00f3n A\u00f1o 2009<\/p>\n<p>Impuesto a las Ganancias &#8211; Dario Rajmilovich &#8211; La Ley &#8211; 2\u00ba Edici\u00f3n A\u00f1o\u00a0 2011<\/p>\n<p>La Renta Mundial o Impuesto a las Ganancias \u00a0&#8211; Dario M. Ratmilovich \u00a0&#8211; La Ley &#8211; A\u00f1o 2001<\/p>\n<p>Ganancias de 1\u00ba,2\u00ba y 4\u00ba categoria &#8211; Josefina Bavera y Gustavo Frankei &#8211; Errepar &#8211; 9\u00ba edicion 2008<\/p>\n<p>Ganancias de 3\u00ba categoria &#8211; Claudia Cerchiara &#8211; Errepar &#8211; 8\u00ba edicion 2008<\/p>\n<p>Imposici\u00f3n sobre el Patrimonio \/ Bienes Personales &#8211; Jos\u00e9 Litak _ Jorge Gebhrat &#8211; Errepar S.A. &#8211; A\u00f1o 1997<\/p>\n<p>Impuesto Sobre los Bienes Personales &#8211; Rigina Berenstein \u00a0&#8211; Reisa &#8211; A\u00f1o 1996<\/p>\n<p>Tratamiento Impositivo &#8211; Dr. Juli\u00e1n A. Mart\u00edn &#8211; Price WaterHouse &#8211; A\u00f1o 1996<\/p>\n<p>Directores y Socios &#8211; Marcelo Percivalle &#8211; Errepar S.A. &#8211; A\u00f1o 1996<\/p>\n<p>Leasing Financiero I &#8211; Eduardo Barreira Delfino &#8211; Editorial Roberto Guido &#8211; A\u00f1o 1996<\/p>\n<p>Leasing Financiero II &#8211; Eduardo Barreira Delfino &#8211; Editorial Roberto Guido &#8211; A\u00f1o 1996<\/p>\n<p>Ley de Impuestos A las Ganancias &#8211; Alfredo Lamagrande &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Regimen de Monotributo \u00a0&#8211; Daniela Rodriguez &#8211; La Ley &#8211; 2\u00ba Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Reorganizaci\u00f3n de Empresas en la Legislaci\u00f3n &#8211; Aurelio Cid &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Reorganizaci\u00f3n de Empresas en la Legislaci\u00f3n &#8211; Aurelio Cid &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Reorganizaci\u00f3n de Empresas en la Legislaci\u00f3n &#8211; Alejandro N. Aladjian &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Fusi\u00f3n Societaria e Impositiva &#8211; Rub\u00e9n O. Asorey &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2004<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Impuestos \u00a0Provinciales <\/strong><\/p>\n<p>Impuesto de Sellos &#8211; Vicente O. Diaz<\/p>\n<p>El Impuesto de Sellos &#8211; Osvaldo Soler &#8211; La Ley &#8211; A\u00f1o 2001<\/p>\n<p>El Impuesto de Sellos &#8211; Osvaldo Soler &#8211; La Ley &#8211; A\u00f1o 2002<\/p>\n<p>Convenio Multilateral &#8211; M. Josefina Bravera y Carlos Vanney &#8211; Errepar S.A. &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 2008<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Interno \u00a0<\/strong><\/p>\n<p>Impuesto Interno \u00a0&#8211; Alberto Balbo y Liliana Pe\u00f1a &#8211; Ediciones Macchi &#8211; A\u00f1o 1996<\/p>\n<p>Impuesto Interno \u00a0&#8211; Dr Sixto Fernandez _ Carlos Lainzillotta &#8211; Ediciones Buyatti &#8211; A\u00f1o 1998<\/p>\n<p>Impuestos Internos \u00a0&#8211; Hilario Laprovita \u00a0&#8211; Depalma &#8211; A\u00f1o 1987<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>IVA <\/strong><\/p>\n<p>El Fisco Opina (Dict\u00e1menes del IVA) &#8211; Ana Monica Riso &#8211; Consultora SRL &#8211; 1\u00b0 Edici\u00f3n a\u00f1o 1997<\/p>\n<p>I.V.A. An\u00e1lisis Econ\u00f3mico, T\u00e9cnico Y Juridico &#8211; Ricardo Fenochietto \u00a0&#8211; Fondo Editorial de Derecho y Econ\u00f3mia \u00a0&#8211; A\u00f1o 2001<\/p>\n<p>I.V.A. An\u00e1lisis Econ\u00f3mico, T\u00e9cnico Y Juridico &#8211; Ricardo Fenochietto \u00a0&#8211; La Ley &#8211; A\u00f1o 2001<\/p>\n<p>An\u00e1lisis del Impuesto Agregado \u00a0&#8211; Federico A. Enrico y Colaboradores &#8211; Fondo Editorial de Derecho y Econ\u00f3mia (FEDyE) \u00a0&#8211; A\u00f1o 2002<\/p>\n<p>An\u00e1lisis del Impuesto Agregado \u00a0&#8211; Federico A. Enrico y Colaboradores &#8211; Fondo Editorial de Derecho y Econ\u00f3mia (FEDyE) \u00a0&#8211; A\u00f1o 2003<\/p>\n<p>An\u00e1lisis Integral del Impuesto Agregado \u00a0&#8211; Marchevski Ruben A. &#8211; Errepar S.A. &#8211; 1\u00b0 Edici\u00f3n a\u00f1o 2006<\/p>\n<p>An\u00e1lisis Integral del Impuesto Agregado \u00a0&#8211; Juan Oklander &#8211; La Ley &#8211; 2\u00b0 Edici\u00f3n a\u00f1o 2009<\/p>\n<p>I.V.A. An\u00e1lisis Intensivo &#8211; Rub\u00e9n A. Marcheusky &#8211; Elias D. Surij\u00f3n &#8211; Ediciones CIMA &#8211; 2\u00b0 Edici\u00f3n A\u00f1o 1992<\/p>\n<p>EL I.V.A. Y las Exportaciones de Bienes y Servicio &#8211; Alfredo R. Sternberg &#8211; Aplicaci\u00f3n Tributaria S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2003<\/p>\n<p>EL I.V.A. Y las Exportaciones de Bienes y Servicio &#8211; Alfredo R. Sternberg &#8211; Aplicaci\u00f3n Tributaria S.A. &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2004<\/p>\n<p>Exportaciones e Impuestos al Valor Agregado &#8211; Federico Mart\u00edn Palavecino &#8211; Errepar S.A. &#8211; A\u00f1o 1997<\/p>\n<p>Recupero de IVA por exportaciones &#8211; Oklander- Baldo &#8211; Harvey &#8211; Policella &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n a\u00f1o 2006<\/p>\n<p>Recupero de IVA por exportaciones &#8211; Oklander- Baldo &#8211; Harvey &#8211; Policella &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n a\u00f1o 2006<\/p>\n<p>Impuesto 1999 &#8211; Isabel Chewpowichz _ Flavia Melzi &#8211; Buyatti &#8211; A\u00f1o 1999<\/p>\n<p>Teor\u00eda y T\u00e9cnica Impositiva I \u00a0&#8211; Dr Juan Carlos Vicchi &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p>Teor\u00eda y T\u00e9cnica Impositiva I I &#8211; Dr. Horacio Ziccardi &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2004<\/p>\n<p>Reforma Tributaria 1999 &#8211; Humberto Bertazza &#8211; Errepar S.A. &#8211; A\u00f1o 1999<\/p>\n<p>Tratamiento Impositivo de Operaciones Financieras &#8211; Julian Mart\u00edn \u00a0&#8211; KPMG &#8211; A\u00f1o 1999<\/p>\n<p>Instrumentos Financieros Derivados &#8211; Julian Mart\u00edn &#8211; Armando Casal &#8211; Errepar &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2008<\/p>\n<p>Fallos de Clausura Impositiva \u00a0&#8211; Luis Giargreco \u00a0&#8211; Buyatti &#8211; A\u00f1o 1998<\/p>\n<p>Nuevas Gestiones de Cobro de Tributos &#8211; Dr. Bertea &#8211; Bolsa de Comercio de Mendoza &#8211; A\u00f1o 2000<\/p>\n<p>El Ajuste Impositivo por inflaci\u00f3n en la Actual Conyuntura &#8211; Angel Scheindel &#8211; La Ley &#8211; A\u00f1o 2003<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Medio Ambiente <\/strong><\/p>\n<p>El Control Internacional de la Aplicaci\u00f3n de los acuerdos Ambientales Universales &#8211; Antonio Cardesa Salzmann &#8211; Marcial Pons &#8211; Ediciones Juridicas Y sociales S.A.<\/p>\n<p>Las Sanciones Tributarias &#8211; Jaime Aneiros Pereira &#8211; Marcial Pons &#8211; Ediciones Juridicas Y sociales S.A.<\/p>\n<p>Fraude y Delito Fiscal en el Iva. Fraude Carrusel,Truchas y otras Tramas &#8211; Luis Manuel Alonso Gonzalez &#8211; Marcial Pons &#8211; Ediciones Juridicas Y sociales S.A.<\/p>\n<p>Cambio Climatico y Regimen Econ\u00f3mico Financiero de los Recursos Narurales &#8211; Antonio Embid Irujo &#8211; Adolfo Iriarte Yanicelli &#8211; Universidad de San Pablo T &#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Principio de Precauci\u00f3n &#8211; Adriana Bestani &#8211; Astrea &#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Derecho Ambiental &#8211; Marcelo L\u00f3pez Alfons\u00edn &#8211; Astrea &#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Procedimiento -Seguridad <\/strong><\/p>\n<p>Procedimiento Tributario y de la Seguridad Social &#8211; \u00a0Giuliani Fonrouge-Susana Navarrine &#8211; Lexis Nexis ( Depalma)<\/p>\n<p>Procedimiento Tributario y de la Seguridad Social &#8211; \u00a0Giuliani Fonrouge-Susana Navarrine &#8211; Abeledo Perrot &#8211; 11\u00aa Edici\u00f3n 2010<\/p>\n<p>Procedimiento ante el Tribunal Fiscal de la Nacion &#8211; Catalina Garcia Vizcaino &#8211; Depalma &#8211; A\u00f1o 1986<\/p>\n<p>Ilicitos Tributarios &#8211; Lilian Gulfinkel de Wendy &#8211; Eduardo a Russo &#8211; Depalma &#8211; A\u00f1o 1987<\/p>\n<p>Ilicitos Tributarios &#8211; Vicente Oscar D\u00edas &#8211; Astrea &#8211; A\u00f1o 2006<\/p>\n<p>Procedimiento Tributario I &#8211; Ernesto C. Celdeiro &#8211; Ediciones Nuevas T\u00e9cnicas &#8211; A\u00f1o 1992<\/p>\n<p>Procedimiento Tributario I &#8211; Ernesto C. Celdeiro &#8211; Ediciones Nuevas T\u00e9cnicas &#8211; A\u00f1o 1992<\/p>\n<p>Procedimiento Tributario II &#8211; Ernesto C. Celdeiro &#8211; Ediciones Nuevas T\u00e9cnicas &#8211; A\u00f1o 1992<\/p>\n<p>Procedimiento Tributario II &#8211; Ernesto C. Celdeiro &#8211; Ediciones Nuevas T\u00e9cnicas &#8211; A\u00f1o 1992<\/p>\n<p>Procedimiento Fiscal en la Pcia. De Tucum\u00e1n &#8211; Luis Alberto Comba &#8211; El Graduado &#8211; A\u00f1o 2000<\/p>\n<p>La Obligaci\u00f3n Tributaria &#8211; Juan Carlos Luqui &#8211; Depalma &#8211; A\u00f1o 1989<\/p>\n<p>Limites al Accionar de la Inspecci\u00f3n Tributaria y el Derecho del Administrado &#8211; Vicente Oscar D\u00edas &#8211; Depalma &#8211; A\u00f1o 1997<\/p>\n<p>Procedimiento Tributario Ley 11683 &#8211; Teresa Gomez &#8211; Carlos Folco &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p>Procedimiento Tributario Ley 11683 &#8211; Teresa Gomez &#8211; Carlos Folco &#8211; La Ley &#8211; 5\u00b0 Edici\u00f3n A\u00f1o 1997<\/p>\n<p>Procedimiento Tributario Ley 11683 &#8211; Teresa Gomez &#8211; Carlos Folco &#8211; La Ley &#8211; 7\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Procedimiento Tributario Ley 11.683 &#8211; decreto 618\/97 &#8211; Ernesto Carlos Celdeiro- Gadea- Imirizaldu &#8211; ERREPAR &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Procedimiento Tributario (Ley 11863) &#8211; Diaz Sieiro-Diego Veljanovich &#8211; Ediciones Macchi &#8211; A\u00f1o 1993<\/p>\n<p>Ley Penal Tributaria y Previsional N\u00b024769 &#8211; Folco Carlos &#8211; Chiar D\u00edaz &#8211; Edici\u00f3n Rubinzal Culzoni &#8211; A\u00f1o 1997<\/p>\n<p>Procedimiento Tributario Ley 11.683 &#8211; Giulliane Fonrouge &#8211; Susana Nevarrine &#8211; Depalma &#8211; 6\u00b0 Edici\u00f3n A\u00f1o 1996<\/p>\n<p>Bloqueo Fiscal &#8211; Analisis Integral T\u00e9cnica y Pr\u00e1ctica \u00a0&#8211; Jos\u00e9 D&#8217;Agostino &#8211; Buyatti &#8211; A\u00f1o 1996<\/p>\n<p>Cuestiones Tributarias &#8211; Gustavo Guerrieri &#8211; Consejo de Profesores de Santiago del Estero &#8211; A\u00f1o 2003<\/p>\n<p>Derecho y Procedimiento Tributario &#8211; Alfredo R. Sternberg &#8211; Errepar S.A. &#8211; A\u00f1o 2000<\/p>\n<p>Derecho y Procedimiento Tributario &#8211; Alfredo R. Sternberg &#8211; Errepar S.A. &#8211; 2\u00ba Edicion 2010<\/p>\n<p>Fallos Plenarios Del Tribunal Fiscal de la Naci\u00f3n \u00a0&#8211; Augusto Rossen &#8211; La Ley &#8211; A\u00f1o 1999<\/p>\n<p>El Procedimiento Tributario y Penal \u00a0&#8211; Teresa Gomez \u00a0&#8211; La Ley &#8211; A\u00f1o 1999<\/p>\n<p>El Procedimiento Tributario y Penal \u00a0&#8211; Teresa Gomez \u00a0&#8211; La Ley &#8211; A\u00f1o 1999<\/p>\n<p>Tratado del regimen Penal Tributario &#8211; Tomo I &#8211; Humberto Bertazza,Norberto Marconi &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tratado del regimen Penal Tributario &#8211; Tomo II &#8211; Humberto Bertazza,Norberto Marconi &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Tratado del regimen Penal Tributario &#8211; Tomo III &#8211; Humberto Bertazza,Norberto Marconi &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Reforma Tributaria Ley 25063 &#8211; Perla Olego de Millisenda &#8211; Buyatti &#8211; A\u00f1o 1999<\/p>\n<p>El Procedimiento Tributario y Penal Atravez de la jurisprudencia \u00a0&#8211; Teresa G\u00f3mez &#8211; La Ley &#8211; A\u00f1o 2001<\/p>\n<p>Procedimientos Administrativos ( Ley 19549 ) &#8211; David A. Halperin &#8211; Ediciones Depalma &#8211; A\u00f1o 1991<\/p>\n<p>Procedimiento Tributarios \u00a0&#8211; Carlos Mar\u00eda Folco \u00a0&#8211; Rubinzal Culzoni Editores \u00a0&#8211; A\u00f1o 2004<\/p>\n<p>Proced. Tributario (Teor\u00eda y Pr\u00e1ctica) &#8211; Sanchez -Coll -Coprrales &#8211; Fedie &#8211; A\u00f1o 2004<\/p>\n<p>Proced. Tributario \u00a0&#8211; Felix Gustavo Guerrieri &#8211; Lucrecia &#8211; 1\u00ba Edicion 2009<\/p>\n<p>La Cuestion Tributaria &#8211; Humberto Bertazza &#8211; La Ley &#8211; 1\u00ba Edicion 2010<\/p>\n<p>Cuestiones\u00a0 Fundamentales de Procedimiento Tributario Nacional &#8211; Ricardo M. Chicolino &#8211; Oscar Fernandez -otros &#8211; Osmar Buyatti &#8211; 21\u00ba Edicion 2007<\/p>\n<p>Limites Juridicos de las Atribuciones de la Inspeccion Tributaria en su Proceder &#8211; Vicente O. Diaz &#8211; AD.Hoc &#8211; 1\u00ba Edicion 2010<\/p>\n<p>Ley de ProcedimientoS Administrativos Aplicada al Proc. Tributario &#8211; Ruben Marchevsky &#8211; Errepar &#8211; 1\u00ba Edicion 2010<\/p>\n<p>Ley de ProcedimientoS Administrativos Aplicada al Proc. Tributario &#8211; Ruben Marchevsky &#8211; Errepar &#8211; 2\u00ba Edicion 2010<\/p>\n<p>Ejecuciones Fiscales &#8211; Carlos Folco &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Ejecuciones Fiscales &#8211; Carlos Folco &#8211; La Ley &#8211; 2\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Ejecuciones Fiscales &#8211; Luis Carranza Torres &#8211; Legis &#8211;<\/p>\n<p>El Delito Fiscal &#8211; Esteba Urresti Fabiana Comes &#8211; AD.HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2008<\/p>\n<p>El Delito Fiscal &#8211; Esteba Urresti Fabiana Comes &#8211; AD.HOC &#8211; 1\u00ba edici\u00f3n A\u00f1o 2011<\/p>\n<p>Regimen Penal Tributario \u00a0&#8211; Hector Belisario Villegas &#8211; La Ley &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2007<\/p>\n<p>Regimen Tributario Argerntino &#8211; Gustavo Naveira-Marcelo Nieto\u00a0 y otros &#8211; Abeledo &#8211; Perrot &#8211; 1\u00ba edici\u00f3n A\u00f1o 2010<\/p>\n<p>Regimen Penal Tributario y Previsional &#8211; Mariano Hernan Borinski y otros &#8211; Rubinzal Culzoni Editores \u00a0&#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Regimen Penal Tributario-Tomo I- ley 24.769 con la reforma de la ley 26.735 \u00a0&#8211; Marcos Alberto Cequeira &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Regimen Penal Tributario-Tomo II- ley 24.769 con la reforma de la ley 26.736 &#8211; Marcos Alberto Cequeira &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Regimen Penal Tributario-Tomo II- ley 24.769 con la reforma de la ley 26.737 &#8211; Marcos Alberto Cequeira &#8211; La Ley &#8211; 2\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Regimen Penal Tributario-Tomo II- ley 24.769 con la reforma de la ley 26.738 &#8211; Marcos Alberto Cequeira &#8211; La Ley &#8211; 3\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>R\u00e9gimen penal Tributario y Previsional &#8211; Mariano Hern\u00e1n Borinski &#8211; Juan Pedro Galvan y otros &#8211; Rubinzal Culzoni Editores \u00a0&#8211; 1\u00ba edici\u00f3n A\u00f1o 2012<\/p>\n<p>Acciones y Recursos em Materia Tributaria &#8211; Rodolfo Spisso &#8211; Abeledo- Perrot &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2010<\/p>\n<p>Temas de Procedimiento Tributarios Nacionales &#8211; Gustavo Guerrieri &#8211; Lucrecia &#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2009<\/p>\n<p>Procedimiento Trib. Naturaleza y Estructura &#8211; Carlos Folco &#8211; Rubinzal Culzoni Editores \u00a0&#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Procedimiento Trib. Naturaleza y Estructura &#8211; Carlos Folco &#8211; Rubinzal Culzoni Editores \u00a0&#8211; 3\u00b0 Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Procedimiento Tributario &#8211; Gabriel Gotlib-Valeria Dalessandro &#8211; ERREPAR &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>La jurisprudencia Tributaria de la Corte Suprema de Justicia de la Naci\u00f3n &#8211;\u00a0 &#8211; ERREPAR &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p>Tratado de la Informacion Tributaria &#8211; Diego Fraga &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2011<\/p>\n<p>Lavado de Dinero y Evasion Fiscal &#8211; Jaime Mecikovsky &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Tratado de Lavado de Activos y Fianciacion del Terrorismo- TOMO I &#8211; Humberto Bertaza, Francisco D,ALBORA &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Tratado de Lavado de Activos y Fianciacion del Terrorismo- TOMO II &#8211; Humberto Bertaza, Francisco D,ALBORA &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Tratado de Lavado de Activos y Fianciacion del Terrorismo- TOMO III &#8211; Humberto Bertaza, Francisco D,ALBORA &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2012<\/p>\n<p>Selecci\u00f3n de Trabajos del Centro de Estudios de Econom\u00eda y Delito -TOMO I &#8211; Vicente Oscar D\u00edaz &#8211; FCE- DE LA UBA &#8211; \u00a0A\u00f1o 2014<\/p>\n<p>Selecci\u00f3n de Trabajos del Centro de Estudios de Econom\u00eda y Delito -TOMO II &#8211; Vicente Oscar D\u00edaz &#8211; FCE- DE LA UBA &#8211; \u00a0A\u00f1o 2015<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Reglamentos <\/strong><\/p>\n<p>Ley 11683 Anotada &#8211; Alejandro N. Lopez &#8211; La Ley &#8211; 1\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sanciones\u00a0 \u00a0<\/strong><\/p>\n<p>Las Sanciones Tributarias Frente a sus Limites constitucionales &#8211; Ju\u00e1n \u00c1lvarez Echag\u00fce &#8211; AD-HOC &#8211; A\u00f1o 2004<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Seguridad Social <\/strong><\/p>\n<p>Nuevo Regim\u00e9n Penal Tributario de la Seguridad Social &#8211; Alberto V. Ber\u00f3n \u00a0&#8211; Errepar S.A. &#8211; A\u00f1o 1997<\/p>\n<p>Tributos de la Seguridad Social &#8211; Sus Vias Recursivas &#8211; Juan Alberto &#8211; Gandara Gustavo &#8211; Aulas y Andamios &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2013<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>T\u00e9cnicas <\/strong><\/p>\n<p>Tecnicas para construir y\u00a0 exponer temas econ\u00f3micosy administrativos &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 1\u00ba edici\u00f3n A\u00f1o 2004<\/p>\n<p>Tecnicas para construir y\u00a0 exponer temas econ\u00f3micosy administrativos &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 1\u00ba edici\u00f3n A\u00f1o 2004<\/p>\n<p>Tecnicas para construir y\u00a0 exponer temas econ\u00f3micosy administrativos &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 1\u00ba edici\u00f3n A\u00f1o 2004<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>TESIS <\/strong><\/p>\n<p>Tesis y Tesinas en Ciencias Economicas &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Tesis y Tesinas en Ciencias Economicas &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Tesis y Tesinas en Ciencias Economicas &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Tesis y Tesinas en Ciencias Economicas &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 2\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Tesis y Tesinas en Ciencias Economicas &#8211; Del carril, De Marco, Usandivaras &#8211; Imprenta central U.N.T. &#8211; 3\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Tributaci\u00f3n &#8211; Constitucional <\/strong><\/p>\n<p>Solve Et Repete &#8211; Jer\u00f3nimo A. Gil Di Paola &#8211; La Ley &#8211; 1\u00ba Edici\u00f3n 2011<\/p>\n<p>Tributaci\u00f3n y Desarrollo Econ\u00f3mico en el Federalismo &#8211; Adolfo Atchabahian &#8211; La Ley &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2011<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Varios <\/strong><\/p>\n<p>Convenio Multilateral &#8211; Enrique Bulit Go\u00f1i &#8211; Depalma &#8211; A\u00f1o 1992<\/p>\n<p>La Empresa &#8211; I. F. Casas &#8211; Inder &#8211; A\u00f1o 1996<\/p>\n<p>Factura de Credito Obligatoria \u00a0&#8211; Eduardo Fabian Duboy&#8217;s &#8211; Errepar S.A. &#8211; A\u00f1o 1997<\/p>\n<p>Factura de Credito Ley 24760 &#8211; Israel Chaluopowicz &#8211; Buyatti &#8211; A\u00f1o 1997<\/p>\n<p>Periodico Econ\u00f3mico Tributario \u00a0&#8211; La Ley \u00a0&#8211; La Ley &#8211; A\u00f1o 1998<\/p>\n<p>Periodico Econ\u00f3mico Tributario \u00a0&#8211; La Ley \u00a0&#8211; La Ley &#8211; A\u00f1o 1999<\/p>\n<p>El Concepto de Empresa en el Ambito Tributario &#8211; Luis O. Fern\u00e1ndez &#8211; La Ley &#8211; A\u00f1o 2004<\/p>\n<p>Ley de Concurso y Quiebra N\u00b0 24552 &#8211; Veronica Martinez de Pretazrini &#8211; Ediciones Macchi &#8211; A\u00f1o 1997<\/p>\n<p>Proyecto de Ley de Coparticipaci\u00f3n Federal de Impuestos &#8211; I.E.F.P.A. &#8211; I. E.F.P.A &#8211; A\u00f1o 1998<\/p>\n<p>Leasing \u00a0&#8211; Nicolas MawMian y Otro &#8211; La Ley &#8211; A\u00f1o 2002<\/p>\n<p>Empadronamiento de Entidades exentas del Impuesto a las Ganancias &#8211; Felix G. Guerrieri &#8211; Buyatti &#8211; A\u00f1o 1999<\/p>\n<p>Aspectos Metodologicos de la Contabilidad &#8211; Dr. Eduardo Scarano &#8211; Impreso Centro &#8211; A\u00f1o 1990<\/p>\n<p>El Impacto de la Tributaci\u00f3n con las Operaciones Internacionales &#8211; Norberto Campagnale &#8211; Silvia Catinot &#8211; La Ley &#8211; A\u00f1o 2000<\/p>\n<p>Zona Franca &#8211; Alvaro Mastroianni- Emilio Bardallo &#8211; Editor Julio Faira &#8211; A\u00f1o 1993<\/p>\n<p>Ley de Reforma Tributaria &#8211; Oscar Peredo-Carlos Bustamante &#8211; 3\u00ba Edici\u00f3n &#8211; A\u00f1o 1996<\/p>\n<p>Quinto Congreso Tributario &#8211; Consejo Prof. Cs. Ecs. Cap. Federal \u00a0&#8211; Consejo de Profesionales Cap. Federal &#8211; A\u00f1o 1998<\/p>\n<p>Sexto Congreso Tributario &#8211; Consejo Prof. Cs. Ecs. Cap. Federal \u00a0&#8211; Consejo de Profesionales Cap. Federal &#8211; A\u00f1o 1998<\/p>\n<p>Postgrado de Esp. Tributaria para el Mercosur &#8211; Univ. De Entre Rios \u00a0&#8211; Universidad &#8211; A\u00f1o 1999<\/p>\n<p>Diccionario Sinonimos y Antonimos &#8211;\u00a0 &#8211; Oceano &#8211; A\u00f1o 2002<\/p>\n<p>Diccionario Com\u00fan &#8211;\u00a0 &#8211;\u00a0 &#8211; A\u00f1o 2002<\/p>\n<p>El Federalismo Fiscal \u00a0&#8211; Felix Borgonovo\/E. Cabanillas &#8211; Criterios Tributarios \u00a0&#8211; A\u00f1o 1995<\/p>\n<p>Tratamiento Tributario &#8211; Fideicomiso Financiero &#8211; Leonardo Hugo Hansen &#8211; Ediciones Macchi &#8211; 1\u00ba edici\u00f3n A\u00f1o 2000<\/p>\n<p>Los Impuestos y el Comercio Exterior Argentino &#8211; Alfredo Stornberg &#8211; Aplicaci\u00f3n Tributaria S.A. &#8211; 3\u00b0 Edicion A\u00f1o 2007<\/p>\n<p>Los Impuestos y el Comercio Exterior Argentino &#8211; Alfredo Stornberg &#8211; Aplicaci\u00f3n Tributaria S.A. &#8211; 3\u00b0 Edicion A\u00f1o 2007<\/p>\n<p>&#8211; Joege Damarco &#8211; La Ley &#8211;<\/p>\n<p>&#8211; Joege Damarco &#8211; La Ley &#8211;<\/p>\n<p>Principios Basicos de Tributaci\u00f3n<\/p>\n<p>Derecho Tributario &#8211; Albert Hensel &#8211; Nova Tesis &#8211; A\u00f1o 2004<\/p>\n<p>Teor\u00eda y T\u00e9cnica Impositiva II &#8211; Angel Schindel &#8211; La Ley &#8211; A\u00f1o 2003<\/p>\n<p>Impuestos a los Consumos &#8211; Juli\u00e1n Mart\u00edn &#8211; KPMG &#8211; 1\u00ba edici\u00f3n A\u00f1o 2004<\/p>\n<p>Codigo Tributario Provincial &#8211; Direccion Gral de Rentas &#8211;\u00a0 &#8211;<\/p>\n<p>Tratado de Fideicomiso &#8211; Gabriel Gotlib- Mario Carregal-Fernando Vaquero<\/p>\n<p>Tratado de Fideicomiso &#8211; Gabriel Gotlib- Mario Carregal-Fernando Vaquero<\/p>\n<p>Elementos de Procedim. Administrativo, Tributario y Penal Tributario &#8211; Gustavo Guerrieri &#8211; Consejo Prof. de Santiago del Estero &#8211; 1\u00ba edici\u00f3n A\u00f1o 2011<\/p>\n<p>5\u00ba Jornada Tributaria,Previcionales,Laborales y Agropecuaria &#8211; Colegio de Graduados en C. E.Rosario &#8211; Consejo Prof. De C. E. &#8211;<\/p>\n<p>6\u00ba Jornada Tributaria,Previcionales,Laborales y Agropecuaria &#8211; Colegio de Graduados en C. E.Rosario &#8211; Consejo Prof. De C. E. &#8211;<\/p>\n<p>Contratos Bancarios &#8211; Sergio Rodriguez Azuero &#8211; Legis &#8211; 6\u00ba edici\u00f3n A\u00f1o 2009<\/p>\n<p>Tributacion en el Comercio Electronico &#8211; \u00a0Silvina Rold\u00e1n &#8211; Buyatti &#8211; 1\u00ba edici\u00f3n A\u00f1o 2006<\/p>\n<p>Planteos en defensa de los Derechos del Contribuyente al Fisco &#8211; Luis Carranza Tores &#8211; Legis &#8211; 1\u00ba edici\u00f3n A\u00f1o 2007<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cat\u00e1logo de libros de la Especializaci\u00f3n en Tributaci\u00f3n Municipales Tasas Municipales -TOMO I &#8211; Enrique Bulit Go\u00f1e -Lexis Nexis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2007 Tasas Municipales -TOMO II -Enrique Bulit Go\u00f1e -Lexis Nexis &#8211; 1\u00b0 Edici\u00f3n A\u00f1o 2007 Tasas Municipales en el Ambito Tributario &#8211; Lorena Almada y Cecilia Matich &#8211; La Ley &#8211; 1\u00b0 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/pages\/317"}],"collection":[{"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/comments?post=317"}],"version-history":[{"count":3,"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/pages\/317\/revisions"}],"predecessor-version":[{"id":324,"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/pages\/317\/revisions\/324"}],"wp:attachment":[{"href":"https:\/\/face.unt.edu.ar\/web\/posgrados\/wp-json\/wp\/v2\/media?parent=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}