{"id":10783,"date":"2020-09-10T02:44:45","date_gmt":"2020-09-10T02:44:45","guid":{"rendered":"https:\/\/face.unt.edu.ar\/web\/?p=10783"},"modified":"2020-09-10T13:13:37","modified_gmt":"2020-09-10T13:13:37","slug":"se-realizo-la-edicion-2020-de-conoce-economicas","status":"publish","type":"post","link":"https:\/\/face.unt.edu.ar\/web\/blog\/se-realizo-la-edicion-2020-de-conoce-economicas\/","title":{"rendered":"Se realiz\u00f3 la edici\u00f3n 2020 de \u201cConoc\u00e9 Econ\u00f3micas\u201d"},"content":{"rendered":"<p style=\"font-weight: 400\">Este mi\u00e9rcoles 9 de septiembre, tuvo lugar la\u00a0<strong>edici\u00f3n 2020 de \u201cConoc\u00e9 Econ\u00f3micas\u201d<\/strong>, la muestra acad\u00e9mica que\u00a0<strong>presenta las distintas carreras que se dictan en nuestra Facultad: Contador P\u00fablico, Licenciatura en Econom\u00eda y Licenciatura en Administraci\u00f3n<\/strong>; que estuvo destinada principalmente a los estudiantes del \u00faltimo a\u00f1o de instituciones educativas del nivel secundario, como as\u00ed tambi\u00e9n al p\u00fablico en general, interesado en cursar alguna de estas carreras.<\/p>\n<p style=\"font-weight: 400\">En esta ocasi\u00f3n, \u201cConoc\u00e9 Econ\u00f3micas\u201d\u00a0<strong>se desarroll\u00f3 por primera vez de forma virtual<\/strong>, debido a las circunstancias de p\u00fablico conocimiento. Fue mediante una\u00a0<strong>transmisi\u00f3n online en vivo<\/strong>, a trav\u00e9s del\u00a0<strong>canal de Youtube de la Facultad<\/strong>\u00a0<strong>FACE \u2013 UNT<\/strong>, organizado por el Sistema de Tutor\u00edas de esta Casa de Estudios.<\/p>\n<p style=\"font-weight: 400\">La bienvenida a los participantes estuvo a cargo de la Secretaria Acad\u00e9mica de la Facultad,\u00a0<strong>Mg. Christine Isgro<\/strong>. Luego se hizo un\u00a0<strong>recorrido virtual por el edificio<\/strong>\u00a0y se realiz\u00f3\u00a0<strong>la presentaci\u00f3n de las tres carreras de grado que ofrece nuestra unidad Acad\u00e9mica<\/strong>.<\/p>\n<p style=\"font-weight: 400\">Durante la jornada\u00a0<strong>docentes de las tres carreras expusieron sobre los contenidos y las incumbencias de las mismas<\/strong>. El\u00a0<strong>Lic. Luis P\u00e9rez Vides<\/strong>, Secretario de Bienestar Estudiantil de la Facultad, present\u00f3 la Licenciatura en Administraci\u00f3n. El\u00a0<strong>Lic. Patricio Cossio<\/strong>, tuvo a su cargo la exposici\u00f3n sobre la Licenciatura en Econom\u00eda, y la\u00a0<strong>Cra. Luciana Castillo<\/strong>, present\u00f3 la carrera de Contador P\u00fablico.<\/p>\n<p style=\"font-weight: 400\">Antes de finalizar los expositores respondieron las consultas que los participantes manifestaron a trav\u00e9s del Chat.<\/p>\n<p style=\"font-weight: 400\"><a href=\"https:\/\/www.youtube.com\/watch?v=i6EuVqpAmU0\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Pueden ver la grabaci\u00f3n de la jornada ingresando al canal de Youtube FACE UNT \u2013 Click aqu\u00ed<\/strong><\/a><\/p>\n<p style=\"font-weight: 400\">Los invitamos a\u00a0<strong>suscribirse al canal<\/strong>\u00a0para recibir material audiovisual de la Facultad.<\/p>\n<p><a href=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-10784 aligncenter\" src=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-300x167.jpg\" alt=\"\" width=\"519\" height=\"289\" srcset=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-300x167.jpg 300w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-1024x569.jpg 1024w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-768x426.jpg 768w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-696x386.jpg 696w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-1068x593.jpg 1068w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt-756x420.jpg 756w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/cp-face-unt.jpg 1277w\" sizes=\"(max-width: 519px) 100vw, 519px\" \/><\/a> <a href=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-10785 aligncenter\" src=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-300x167.jpg\" alt=\"\" width=\"515\" height=\"286\" srcset=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-300x167.jpg 300w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-1024x571.jpg 1024w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-768x428.jpg 768w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-696x385.jpg 696w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-1068x596.jpg 1068w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt-753x420.jpg 753w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/le-face-unt.jpg 1271w\" sizes=\"(max-width: 515px) 100vw, 515px\" \/><\/a> <a href=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-10786 aligncenter\" src=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-300x168.jpg\" alt=\"\" width=\"529\" height=\"296\" srcset=\"https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-300x168.jpg 300w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-1024x572.jpg 1024w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-768x429.jpg 768w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-696x389.jpg 696w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-1068x596.jpg 1068w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt-752x420.jpg 752w, https:\/\/face.unt.edu.ar\/web\/wp-content\/uploads\/2020\/09\/la-face-unt.jpg 1277w\" sizes=\"(max-width: 529px) 100vw, 529px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 9 de septiembre, tuvo lugar la\u00a0edici\u00f3n 2020 de \u201cConoc\u00e9 Econ\u00f3micas\u201d, la muestra acad\u00e9mica que\u00a0presenta las distintas carreras que se dictan en nuestra Facultad: Contador P\u00fablico, Licenciatura en Econom\u00eda y Licenciatura en Administraci\u00f3n; que estuvo destinada principalmente a los estudiantes del \u00faltimo a\u00f1o de instituciones educativas del nivel secundario, como as\u00ed tambi\u00e9n al p\u00fablico [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10787,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4],"tags":[670,36],"_links":{"self":[{"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/posts\/10783"}],"collection":[{"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/comments?post=10783"}],"version-history":[{"count":3,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/posts\/10783\/revisions"}],"predecessor-version":[{"id":10793,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/posts\/10783\/revisions\/10793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/media\/10787"}],"wp:attachment":[{"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/media?parent=10783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/categories?post=10783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/face.unt.edu.ar\/web\/wp-json\/wp\/v2\/tags?post=10783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}